{"id":1007724,"date":"2025-08-15T17:01:01","date_gmt":"2025-08-15T20:01:01","guid":{"rendered":"https:\/\/psr.marke.com.br\/colaborador\/joao-pedro-bastos-msc\/"},"modified":"2025-08-15T17:01:01","modified_gmt":"2025-08-15T20:01:01","slug":"joao-pedro-bastos-msc","status":"publish","type":"colaborador","link":"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/","title":{"rendered":"Jo\u00e3o Pedro Bastos, Msc"},"content":{"rendered":"<div class=\"vgblk-rw-wrapper limit-wrapper\">Desde 2014, en PSR, ha desarrollado proyectos centrados en el an\u00e1lisis de los mercados el\u00e9ctricos internacionales, la modelizaci\u00f3n de mercados, las proyecciones de precios de la energ\u00eda y la formulaci\u00f3n de pol\u00edticas para el sector. Ha liderado la debida diligencia de mercado en transacciones (fusiones y adquisiciones, y financiamiento) de activos de electricidad y gas en varios pa\u00edses de Latinoam\u00e9rica. Tambi\u00e9n ha impartido cursos sobre dise\u00f1o de mercados el\u00e9ctricos, subastas de energ\u00eda y modelizaci\u00f3n de sistemas el\u00e9ctricos.<\/p>\n<p>&lt;b&gt;Antecedentes Acad\u00e9micos&lt;\/b&gt;<\/p>\n<p>Maestr\u00eda en Ingenier\u00eda El\u00e9ctrica \u2013 PUC-Rio<br \/>\nLicenciatura en Ingenier\u00eda de Producci\u00f3n \u2013 UFRJ<br \/>\n&lt;b&gt;Experiencia Profesional&lt;\/b&gt;<\/p>\n<p>Experiencia en debida diligencia de mercado en transacciones de activos de electricidad y gas en varios pa\u00edses.<br \/>\nAn\u00e1lisis de los mercados energ\u00e9ticos internacionales.<br \/>\nProyecciones de precios de la energ\u00eda en varios pa\u00edses.<br \/>\nDesarrollo de estudios para la planificaci\u00f3n de la expansi\u00f3n de la generaci\u00f3n el\u00e9ctrica.<br \/>\nConferencista en talleres y seminarios nacionales e internacionales.<\/p><\/div>\n<p><!-- .vgblk-rw-wrapper --><\/p>\n","protected":false},"featured_media":1007725,"template":"","meta":{"_acf_changed":false},"categoria-de-equipe":[341],"class_list":["post-1007724","colaborador","type-colaborador","status-publish","has-post-thumbnail","hentry","categoria-de-equipe-consultoria-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jo\u00e3o Pedro Bastos, Msc<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jo\u00e3o Pedro Bastos, Msc\" \/>\n<meta property=\"og:description\" content=\"Desde 2014, en PSR, ha desarrollado proyectos centrados en el an\u00e1lisis de los mercados el\u00e9ctricos internacionales, la modelizaci\u00f3n de mercados,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/\" \/>\n<meta property=\"og:site_name\" content=\"PSR Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/psrenergy\" \/>\n<meta property=\"og:image\" content=\"https:\/\/psr.marke.com.br\/wp-content\/uploads\/2025\/07\/Joao-Pedro-Bastos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"255\" \/>\n\t<meta property=\"og:image:height\" content=\"206\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@psrenergy\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/\",\"url\":\"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/\",\"name\":\"Jo\u00e3o Pedro Bastos, Msc\",\"isPartOf\":{\"@id\":\"https:\/\/psr.marke.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/psr.marke.com.br\/wp-content\/uploads\/2025\/07\/Joao-Pedro-Bastos.png\",\"datePublished\":\"2025-08-15T20:01:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/#primaryimage\",\"url\":\"https:\/\/psr.marke.com.br\/wp-content\/uploads\/2025\/07\/Joao-Pedro-Bastos.png\",\"contentUrl\":\"https:\/\/psr.marke.com.br\/wp-content\/uploads\/2025\/07\/Joao-Pedro-Bastos.png\",\"width\":255,\"height\":206},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/psr.marke.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colaboradores\",\"item\":\"https:\/\/psr.marke.com.br\/es\/equipe\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jo\u00e3o Pedro Bastos, Msc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/psr.marke.com.br\/es\/#website\",\"url\":\"https:\/\/psr.marke.com.br\/es\/\",\"name\":\"PSR\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/psr.marke.com.br\/es\/#organization\"},\"alternateName\":\"PSR Energy Consulting\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/psr.marke.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/psr.marke.com.br\/es\/#organization\",\"name\":\"PSR\",\"alternateName\":\"PSR Energy Consulting\",\"url\":\"https:\/\/psr.marke.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/psr.marke.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/psr.marke.com.br\/wp-content\/uploads\/2023\/03\/logo-psr.svg\",\"contentUrl\":\"https:\/\/psr.marke.com.br\/wp-content\/uploads\/2023\/03\/logo-psr.svg\",\"width\":1056,\"height\":816,\"caption\":\"PSR\"},\"image\":{\"@id\":\"https:\/\/psr.marke.com.br\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/psrenergy\",\"https:\/\/x.com\/psrenergy\",\"https:\/\/www.instagram.com\/psrenergy\/\",\"https:\/\/www.linkedin.com\/company\/psrenergy\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jo\u00e3o Pedro Bastos, Msc","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Jo\u00e3o Pedro Bastos, Msc","og_description":"Desde 2014, en PSR, ha desarrollado proyectos centrados en el an\u00e1lisis de los mercados el\u00e9ctricos internacionales, la modelizaci\u00f3n de mercados,...","og_url":"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/","og_site_name":"PSR Energy","article_publisher":"https:\/\/www.facebook.com\/psrenergy","og_image":[{"width":255,"height":206,"url":"https:\/\/psr.marke.com.br\/wp-content\/uploads\/2025\/07\/Joao-Pedro-Bastos.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@psrenergy","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/","url":"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/","name":"Jo\u00e3o Pedro Bastos, Msc","isPartOf":{"@id":"https:\/\/psr.marke.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/#primaryimage"},"image":{"@id":"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/#primaryimage"},"thumbnailUrl":"https:\/\/psr.marke.com.br\/wp-content\/uploads\/2025\/07\/Joao-Pedro-Bastos.png","datePublished":"2025-08-15T20:01:01+00:00","breadcrumb":{"@id":"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/#primaryimage","url":"https:\/\/psr.marke.com.br\/wp-content\/uploads\/2025\/07\/Joao-Pedro-Bastos.png","contentUrl":"https:\/\/psr.marke.com.br\/wp-content\/uploads\/2025\/07\/Joao-Pedro-Bastos.png","width":255,"height":206},{"@type":"BreadcrumbList","@id":"https:\/\/psr.marke.com.br\/es\/colaborador\/joao-pedro-bastos-msc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/psr.marke.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"Colaboradores","item":"https:\/\/psr.marke.com.br\/es\/equipe\/"},{"@type":"ListItem","position":3,"name":"Jo\u00e3o Pedro Bastos, Msc"}]},{"@type":"WebSite","@id":"https:\/\/psr.marke.com.br\/es\/#website","url":"https:\/\/psr.marke.com.br\/es\/","name":"PSR","description":"","publisher":{"@id":"https:\/\/psr.marke.com.br\/es\/#organization"},"alternateName":"PSR Energy Consulting","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/psr.marke.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/psr.marke.com.br\/es\/#organization","name":"PSR","alternateName":"PSR Energy Consulting","url":"https:\/\/psr.marke.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/psr.marke.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/psr.marke.com.br\/wp-content\/uploads\/2023\/03\/logo-psr.svg","contentUrl":"https:\/\/psr.marke.com.br\/wp-content\/uploads\/2023\/03\/logo-psr.svg","width":1056,"height":816,"caption":"PSR"},"image":{"@id":"https:\/\/psr.marke.com.br\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/psrenergy","https:\/\/x.com\/psrenergy","https:\/\/www.instagram.com\/psrenergy\/","https:\/\/www.linkedin.com\/company\/psrenergy\/"]}]}},"_links":{"self":[{"href":"https:\/\/psr.marke.com.br\/es\/wp-json\/wp\/v2\/colaborador\/1007724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/psr.marke.com.br\/es\/wp-json\/wp\/v2\/colaborador"}],"about":[{"href":"https:\/\/psr.marke.com.br\/es\/wp-json\/wp\/v2\/types\/colaborador"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/psr.marke.com.br\/es\/wp-json\/wp\/v2\/media\/1007725"}],"wp:attachment":[{"href":"https:\/\/psr.marke.com.br\/es\/wp-json\/wp\/v2\/media?parent=1007724"}],"wp:term":[{"taxonomy":"categoria-de-equipe","embeddable":true,"href":"https:\/\/psr.marke.com.br\/es\/wp-json\/wp\/v2\/categoria-de-equipe?post=1007724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}